{"id":4698,"date":"2022-09-01T17:45:17","date_gmt":"2022-09-01T20:45:17","guid":{"rendered":"https:\/\/www.acordocerto.com.br\/?p=4698"},"modified":"2024-05-13T17:09:55","modified_gmt":"2024-05-13T20:09:55","slug":"o-que-e-cadastro-unico","status":"publish","type":"post","link":"https:\/\/www.acordocerto.com.br\/blog\/o-que-e-cadastro-unico\/","title":{"rendered":"O que \u00e9 o Cadastro \u00danico? Aprenda a\u00a0se Inscrever  no Cad\u00danico para Garantir Aux\u00edlios do Governo"},"content":{"rendered":"\n<p>O Cadastro \u00danico&nbsp;\u00e9 uma ferramenta muito importante para o Governo, pois \u00e9 usada para distribuir benef\u00edcios e aux\u00edlios sociais para milh\u00f5es de fam\u00edlia que est\u00e3o em situa\u00e7\u00e3o de baixa renda, pobreza e extrema pobreza. &nbsp;<\/p>\n\n\n\n<p>Ent\u00e3o, se voc\u00ea quer se inscrever em algum benef\u00edcio do Governo, como por exemplo o Aux\u00edlio Brasil, com certeza voc\u00ea ter\u00e1 que iniciar fazendo o seu Cadastro \u00danico.&nbsp;<\/p>\n\n\n\n<div class=\"cta-btn-block\">\n  <a class=\"cta-btn\" href=\"https:\/\/app.acordocerto.com.br\/login?utm_source=blog&amp;utm_medium=acordocerto&amp;utm_term=cta-post\" target=\"_blank\">Consulte seu CPF<\/a>\n<\/div>\n\n\n\n<p>Conhe\u00e7a tudo sobre ele abaixo e veja como fazer o seu gratuitamente. &nbsp;<\/p>\n\n\n\n<p>Sem tempo para ler? Clique no play abaixo para ouvir o conte\u00fado&nbsp;?<\/p>\n\n\n\n<iframe width=\"100%\" height=\"83\" scrolling=\"no\" src=\"https:\/\/go.vooozer.com\/embed\/03b70a50\" frameborder=\"0\" title=\"Narra\u00e7\u00e3o humana do artigo\" style=\"height: 83px !important;\" allowfullscreen=\"\"><\/iframe>\n\n\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O que \u00e9 Cadastro \u00danico<\/strong>?<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Como Se Cadastrar no Cadastro \u00danico 2024: Passo a Passo Completo - Acordo Certo\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/UNI1xYeEjjI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>O Cadastro \u00danico do Governo Federal, ou somente Cad\u00danico, \u00e9 um registro que as fam\u00edlias que s\u00e3o de baixa renda do Brasil precisam ter. &nbsp;<\/p>\n\n\n\n<p>Este cadastro foi desenvolvido pelo Governo e tem como objetivo centralizar dados e informa\u00e7\u00f5es destas fam\u00edlias, para que ent\u00e3o elas possam participar de programas sociais e receber aux\u00edlios, direitos e benef\u00edcios. &nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n\n\n\n<p>Apesar de ter sido criado pelo Governo, o Cad\u00danico \u00e9 administrado e atualizado pelas prefeituras de cada cidade do pa\u00eds.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Para que serve o Cad\u00danico?<\/strong>&nbsp;<\/h2>\n\n\n\n<p>O Cadastro \u00fanico serve para centralizar as informa\u00e7\u00f5es das fam\u00edlias que s\u00e3o de baixa renda do Brasil. Com os dados em um \u00fanico lugar, fica mais f\u00e1cil para o Governo detectar essas fam\u00edlias e ent\u00e3o liberar benef\u00edcios e aux\u00edlios.&nbsp;<\/p>\n\n\n\n<p>Como este cadastro j\u00e1 est\u00e1 padronizado, sempre que novos programas sociais s\u00e3o desenvolvidos, n\u00e3o \u00e9 necess\u00e1rio elaborar um novo tipo de cadastro: se o benef\u00edcio \u00e9 oferecido para fam\u00edlias de baixa renda, ent\u00e3o basta o Governo associ\u00e1-lo ao Cad\u00danico, pois assim j\u00e1 conseguir\u00e1 ter acesso \u00e0s informa\u00e7\u00f5es e encontrar as fam\u00edlias que est\u00e3o nesta situa\u00e7\u00e3o&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<div class=\"cta-btn-block\">\n  <a class=\"cta-btn\" href=\"https:\/\/app.acordocerto.com.br\/login?utm_source=blog&amp;utm_medium=acordocerto&amp;utm_term=cta-post\" target=\"_blank\">Consulte seu CPF<\/a>\n<\/div>\n\n\n\n<p>O Cad\u00danico tamb\u00e9m auxilia as pr\u00f3prias fam\u00edlias a fazerem os seus cadastros, manterem as informa\u00e7\u00f5es atualizadas e tamb\u00e9m encontrarem tudo que precisam saber sobre benef\u00edcios, desde a inscri\u00e7\u00e3o neles, fazer o acompanhamento de status, conferir prazos de recebimento de valores, entre outros. &nbsp;<\/p>\n\n\n\n<p>Atualmente, Cad\u00danico est\u00e1 tudo atualizado e pode ser acessado pela internet, <a href=\"https:\/\/cadunico.dataprev.gov.br\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\">atrav\u00e9s do site<\/a> e aplicativo, o que facilita bastante o acesso dos benefici\u00e1rios.&nbsp;<\/p>\n\n\n\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.acordocerto.com.br\/blog\/poupanca-social-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Poupan\u00e7a Social Digital<\/a> (Caixa Tem): Entenda o que \u00e9, como funciona e quanto rende&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quem pode se inscrever no Cadastro \u00danico?<\/strong><\/h2>\n\n\n\n<p>O Cadastro \u00danico \u00e9 oferecido para fam\u00edlias de baixa renda que se enquadram nos seguintes requisitos e conseguem comprovar: &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.acordocerto.com.br\/blog\/renda-familiar-per-capita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Renda mensal familiar per capita<\/a> (por cabe\u00e7a) de at\u00e9 meio <a href=\"https:\/\/www.acordocerto.com.br\/blog\/salario-minimo\/\">sal\u00e1rio m\u00ednimo<\/a><\/li>\n\n\n\n<li>Renda mensal familiar total de at\u00e9 3 sal\u00e1rios-m\u00ednimos, ou ent\u00e3o at\u00e9 R$ 3.636 (o sal\u00e1rio m\u00ednimo em 2022 tem o valor de R$1.212,00)&nbsp;<\/li>\n\n\n\n<li>Renda mensal familiar total de at\u00e9 3 sal\u00e1rios m\u00ednimos, ou ent\u00e3o at\u00e9 R$ 3.636 e que j\u00e1 tenham um v\u00ednculo com algum programa social (ou que tenham interesse de participar de algum programa)&nbsp;<\/li>\n\n\n\n<li>Pessoas que est\u00e3o em situa\u00e7\u00e3o de rua (sozinhas ou em fam\u00edlia)&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como se inscrever no Cad\u00danico <\/strong><\/h2>\n\n\n\n<p>Para se inscrever no Cad\u00danico, o primeiro passo \u00e9 escolher uma pessoa que ser\u00e1 a representante da fam\u00edlia, tamb\u00e9m conhecido como Respons\u00e1vel Familiar. Esta ficar\u00e1 respons\u00e1vel por cadastrar os dados de todos os integrantes e por passar pela entrevista. &nbsp;<\/p>\n\n\n\n<p>Por isso, se a sua fam\u00edlia se enquadra em pelo menos uma das regras acima, ent\u00e3o voc\u00ea pode inscrev\u00ea-la no Cad\u00danico. &nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<div class=\"cta-btn-block\">\n  <a class=\"cta-btn\" href=\"https:\/\/app.acordocerto.com.br\/login?utm_source=blog&amp;utm_medium=acordocerto&amp;utm_term=cta-post\" target=\"_blank\">Consulte seu CPF<\/a>\n<\/div>\n\n\n\n<p>O mais recomendado \u00e9 que o representante seja uma pessoa do sexo feminino, logo, pode ser a mulher respons\u00e1vel pela fam\u00edlia. Caso a sua fam\u00edlia n\u00e3o tenha uma representante mulher, est\u00e1 tudo bem tamb\u00e9m: voc\u00ea ainda poder\u00e1 seguir com o seu cadastro. Para isso, basta ter mais do que 21 anos.&nbsp;<\/p>\n\n\n\n<p>Para iniciar, \u00e9 preciso reunir todos os documentos da fam\u00edlia e fazer um pr\u00e9 cadastro: este pode ser feito pelo <a href=\"https:\/\/cadunico.dataprev.gov.br\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\">site<\/a> ou aplicativo Meu Cadastro \u00danico, ou Meu Cad\u00danico. &nbsp;<\/p>\n\n\n\n<p>Depois de cadastrar todas as informa\u00e7\u00f5es da fam\u00edlia, a Respons\u00e1vel Familiar precisar\u00e1 ir em um posto de atendimento do Cadastro \u00danico de forma presencial, levando os documentos de identifica\u00e7\u00e3o pr\u00f3prios e os dos seus familiares, como filhos, esposo, etc. Esse processo \u00e9&nbsp;feito para validar a identidade de cada pessoa e para adicionar dados complementares ao registro da fam\u00edlia. &nbsp;<\/p>\n\n\n\n<p>E n\u00e3o se esque\u00e7a: a Respons\u00e1vel Familiar ter\u00e1 o prazo de 120 dias depois do pr\u00e9 cadastro para ir presencialmente ao posto de atendimento. &nbsp;<\/p>\n\n\n\n<p>Esta fase presencial \u00e9 conhecida como \u201centrevista\u201d e tem a dura\u00e7\u00e3o de pelo menos uma hora, ent\u00e3o n\u00e3o esque\u00e7a de se programar e reservar um bom tempo para finalizar o seu cadastro no Cad\u00danico.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Documentos necess\u00e1rios <\/strong><\/h3>\n\n\n\n<p>Para fazer o cadastro do Cad\u00danico, \u00e9 preciso apresentar pelo menos um dos documentos abaixo de cada familiar: &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Carteira de Identidade <a href=\"https:\/\/www.acordocerto.com.br\/blog\/rg-o-que-e-guia-completo\/\" target=\"_blank\" rel=\"noreferrer noopener\">RG<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.acordocerto.com.br\/blog\/cpf-o-que-e\/\">CPF<\/a>&nbsp;ou <a href=\"https:\/\/www.acordocerto.com.br\/blog\/nova-carteira-de-identidade-nacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">Novo CPF<\/a><\/li>\n\n\n\n<li>Certid\u00e3o de Nascimento ou de&nbsp;Casamento&nbsp;<\/li>\n\n\n\n<li>T\u00edtulo de Eleitor (<a href=\"https:\/\/www.acordocerto.com.br\/blog\/e-titulo\/\" target=\"_blank\" rel=\"noreferrer noopener\">e-t\u00edtulo<\/a>)<\/li>\n\n\n\n<li>Carteira de Trabalho&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como consultar o cadastro \u00fanico pelo CPF<\/strong><\/h2>\n\n\n\n<p>Voc\u00ea pode consultar sempre o seu cadastro de forma online e gratuita pelo aplicativo ou site Meu Cadastro \u00danico. &nbsp;<\/p>\n\n\n\n<p>Siga os passos abaixo para consultar pelo app Meu Cad\u00danico:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acesse a lojinha do seu celular e baixe o app Meu Cad\u00danico (tem para Android e IOS)&nbsp;<\/li>\n\n\n\n<li>Depois de baixar, abra o app&nbsp;<\/li>\n\n\n\n<li>Se for a primeira vez acessando o app, ele ter\u00e1 um tutorial para apreender usar. Para pular, \u00e9 s\u00f3 clicar em \u201cpr\u00f3ximo\u201d&nbsp;<\/li>\n\n\n\n<li>Depois aparecer\u00e1 uma tela com todos os servi\u00e7os relacionados ao Cadastro \u00danico, como consulta por CPF, consulta simples, consulta completa, pr\u00e9-cadastro, comprovante de cadastro, atualiza\u00e7\u00e3o cadastra por confirma\u00e7\u00e3o, meus benef\u00edcios&nbsp;e postos de atendimento. Clique em \u201cconsulta por CPF\u201d&nbsp;<\/li>\n\n\n\n<li>Por fim, digite o n\u00famero do seu CPF e a sua data de nascimento. Depois clique em \u201cConsultar\u201d. &nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"366\" height=\"463\" src=\"https:\/\/www.acordocerto.com.br\/wp-content\/uploads\/2022\/09\/Screenshot_5.png\" alt=\"Consultar CadUnico pelo CPF\" class=\"wp-image-4699\" srcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2022\/09\/Screenshot_5.png 366w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2022\/09\/Screenshot_5-237x300.png 237w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2022\/09\/Screenshot_5-150x190.png 150w\" sizes=\"(max-width: 366px) 100vw, 366px\" \/><figcaption class=\"wp-element-caption\">Reprodu\u00e7\u00e3o: App Store<\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>Atualizar o cadastro \u00fanico pela internet<\/strong><\/h2>\n\n\n\n<p>A atualiza\u00e7\u00e3o do seu cadastro no Cad\u00danico pode ser feita de forma 100% online e \u00e9 um processo obrigat\u00f3rio, que deve ser feito por todas as fam\u00edlias inscritas no m\u00e1ximo a cada dois anos para garantir o recebimento dos benef\u00edcios.&nbsp;<\/p>\n\n\n\n<div class=\"cta-btn-block\">\n  <a class=\"cta-btn\" href=\"https:\/\/app.acordocerto.com.br\/login?utm_source=blog&amp;utm_medium=acordocerto&amp;utm_term=cta-post\" target=\"_blank\">Consulte seu CPF<\/a>\n<\/div>\n\n\n\n<p>Antes, as atualiza\u00e7\u00f5es s\u00f3 podiam ser feitas presencialmente no CRAS (Centro de Refer\u00eancia da Assist\u00eancia Social), mas com a atualiza\u00e7\u00e3o do aplicativo e site, agora o processo pode ser feito pela internet. &nbsp;<\/p>\n\n\n\n<p>E em quais situa\u00e7\u00f5es voc\u00ea deve atualizar o seu cadastro \u00fanico? Lembre-se de alterar as informa\u00e7\u00f5es quando: &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Algum novo familiar nascer; &nbsp;<\/li>\n\n\n\n<li>Algum familiar falecer;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Algum familiar mudar de casa&nbsp;<\/li>\n\n\n\n<li>Quando a fam\u00edlia muda&nbsp;de endere\u00e7o &nbsp;<\/li>\n\n\n\n<li>Quando as crian\u00e7as da fam\u00edlia entram ou mudam de&nbsp;escola;&nbsp;<\/li>\n\n\n\n<li>Quando a fam\u00edlia tem alguma varia\u00e7\u00e3o de renda, seja para menos ou para mais&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Veja as formas de atualizar o seu cadastro: &nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Acessando o site ou aplicativo Meu Cad\u00danico diretamente pelo CPF ou NIS&nbsp;<\/li>\n\n\n\n<li>Acessando o site ou aplicativo Meu Cad\u00danico com login e senha no site do Governo: o site do Governo oferece v\u00e1rios servi\u00e7os online, consultar CPF, consultar receita federal, consultar Meu <a href=\"https:\/\/www.acordocerto.com.br\/blog\/o-que-e-inss\/\" target=\"_blank\" rel=\"noreferrer noopener\">INSS<\/a>, inscri\u00e7\u00e3o do ENEM, fazer imposto de renda, entre outros. Por isso, se voc\u00ea n\u00e3o tem este login, <a href=\"https:\/\/sso.acesso.gov.br\/login?client_id=contas.acesso.gov.br&amp;authorization_id=182fab651f2\" target=\"_blank\" rel=\"noreferrer noopener\">basta acessar o Portal Oficial do Governo clicando aqui.<\/a><\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p>N\u00e3o se esque\u00e7a que independente da atualiza\u00e7\u00e3o, voc\u00ea precisar\u00e1 ter em m\u00e3os o CPF ou T\u00edtulo de Eleitor do Respons\u00e1vel Familiar e pelo menos um dos seguintes documentos para cada pessoa da fam\u00edlia: &nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>CPF&nbsp;<\/li>\n\n\n\n<li>RG&nbsp;<\/li>\n\n\n\n<li>T\u00edtulo de eleitor&nbsp;<\/li>\n\n\n\n<li>Certid\u00e3o (de nascimento ou casamento&nbsp;<\/li>\n\n\n\n<li>Carteira de Trabalho&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Veja tamb\u00e9m: <a href=\"https:\/\/www.acordocerto.com.br\/blog\/consultar-nis-pelo-cpf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Consultar NIS pelo CPF: Passo a passo completo<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Programas que utilizam Cad\u00danico<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Conhe\u00e7a os principais programas que utilizam o Cadastro \u00danico:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cadastro \u00fanico <a href=\"https:\/\/www.acordocerto.com.br\/blog\/auxilio-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aux\u00edlio Brasil<\/a>;<\/li>\n\n\n\n<li>Cadastro \u00fanico<a href=\"https:\/\/www.acordocerto.com.br\/blog\/consultar-bolsa-familia-pelo-cpf\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Bolsa Fam\u00edlia<\/a>;&nbsp;<\/li>\n\n\n\n<li>Programa Tarifa Social de Energia El\u00e9trica;<\/li>\n\n\n\n<li>Tarifa social de \u00e1gua;<\/li>\n\n\n\n<li>Isen\u00e7\u00e3o de Taxas em Concursos P\u00fablicos, tanto federais quanto&nbsp;distritais;<\/li>\n\n\n\n<li>ID Jovem;<\/li>\n\n\n\n<li>Carteira do Idoso;&nbsp;<\/li>\n\n\n\n<li>Programa Casa Verde e Amarela;&nbsp;<\/li>\n\n\n\n<li>Programa Bolsa Verde;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.acordocerto.com.br\/blog\/beneficio-de-prestacao-continuada\/\" target=\"_blank\" rel=\"noreferrer noopener\">Benef\u00edcio de Presta\u00e7\u00e3o Continuada<\/a> (BPC);<\/li>\n\n\n\n<li>Aux\u00edlio G\u00e1s dos Brasileiros;<\/li>\n\n\n\n<li>Telefone Popular;<\/li>\n\n\n\n<li>Fomento \u00e0s atividades produtivas rurais;<\/li>\n\n\n\n<li>Programas habitacionais;<\/li>\n\n\n\n<li>Carta social;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.acordocerto.com.br\/blog\/auxilio-emergencial-quem-tem-direito\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aux\u00edlio emergencial<\/a> durante a pandemia da Covid-19;<\/li>\n\n\n\n<li>Programa Nossa Gente Paran\u00e1 \u2013 Fam\u00edlia Paranaense;<\/li>\n\n\n\n<li>Programa Leite das Crian\u00e7as;<\/li>\n\n\n\n<li><a href=\"https:\/\/www.acordocerto.com.br\/blog\/bolsa-do-povo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bolsa do Povo<\/a><\/li>\n<\/ul>\n\n\n\n<p> <\/p>\n\n\n\t\t<div class=\"web-stories-list alignnone has-archive-link is-view-type-grid columns-2 is-style-default\" data-id=\"1\">\n\t\t\t<div class=\"web-stories-list__inner-wrapper\" style=\"\">\n\t\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/calendario-bolsa-familia-novembro\/\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/07\/cropped-Calendario-bolsa-familia-agosto-2023.jpg\"\n\t\t\t\t\t\talt=\"Calend\u00e1rio Bolsa Fam\u00edlia Novembro 2024\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/07\/cropped-Calendario-bolsa-familia-agosto-2023.jpg 640w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/07\/cropped-Calendario-bolsa-familia-agosto-2023-150x200.jpg 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"auto, (max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tCalend\u00e1rio Bolsa Fam\u00edlia Novembro 2024\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__author\">\n\t\t\t\t\tPor Beatriz Torres\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/quanto-rebeca-andrade-pagara-de-imposto\/\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-644541144-4509353-quanto-rebeca-andrade-ja-faturou-com-med-1400x823-2.webp\"\n\t\t\t\t\t\talt=\"Quanto Rebeca Andrade pagar\u00e1 de imposto por suas medalhas?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-644541144-4509353-quanto-rebeca-andrade-ja-faturou-com-med-1400x823-2.webp 640w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-644541144-4509353-quanto-rebeca-andrade-ja-faturou-com-med-1400x823-2-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"auto, (max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tQuanto Rebeca Andrade pagar\u00e1 de imposto por suas medalhas?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__author\">\n\t\t\t\t\tPor Renata Martins\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/simone-biles-e-influencers-brasileiras\/\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-simone-biles-medalha-de-ouro-olimpiada-e1722382998736.webp\"\n\t\t\t\t\t\talt=\"Simone Biles versus Influencers Brasileiras: Quem ganha mais?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-simone-biles-medalha-de-ouro-olimpiada-e1722382998736.webp 640w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/08\/cropped-simone-biles-medalha-de-ouro-olimpiada-e1722382998736-150x200.webp 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"auto, (max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tSimone Biles versus Influencers Brasileiras: Quem ganha mais?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__author\">\n\t\t\t\t\tPor Renata Martins\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/5-habitos-faceis-para-economizar-no-dia-a-dia\/\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/08\/cropped-nubelson-fernandes-rfoH17_F7F8-unsplash-scaled-1.jpg\"\n\t\t\t\t\t\talt=\"5 H\u00e1bitos F\u00e1ceis para Economizar no Dia a Dia!\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/08\/cropped-nubelson-fernandes-rfoH17_F7F8-unsplash-scaled-1.jpg 640w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2023\/08\/cropped-nubelson-fernandes-rfoH17_F7F8-unsplash-scaled-1-150x200.jpg 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"auto, (max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\t5 H\u00e1bitos F\u00e1ceis para Economizar no Dia a Dia!\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__author\">\n\t\t\t\t\tPor Carolina Jacob\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tclass=\"web-stories-list__story\"\n\t\t\t\tdata-wp-interactive=\"web-stories-block\"\n\t\t\t\tdata-wp-context='{\"instanceId\":1}'\t\t\t\tdata-wp-on--click=\"actions.open\"\n\t\t\t\tdata-wp-on-window--popstate=\"actions.onPopstate\"\n\t\t\t\t>\n\t\t\t\t\t\t\t<div class=\"web-stories-list__story-poster\">\n\t\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/afinal-quanto-o-futebol-solidario-arrecadou\/\">\n\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/05\/cropped-futebol-solidario-2.jpg\"\n\t\t\t\t\t\talt=\"Afinal, quanto o Futebol Solid\u00e1rio arrecadou?\"\n\t\t\t\t\t\twidth=\"185\"\n\t\t\t\t\t\theight=\"308\"\n\t\t\t\t\t\t\t\t\t\t\t\t\tsrcset=\"https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/05\/cropped-futebol-solidario-2.jpg 640w, https:\/\/www.acordocerto.com.br\/blog\/wp-content\/uploads\/2024\/05\/cropped-futebol-solidario-2-150x200.jpg 150w\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tsizes=\"auto, (max-width: 640px) 100vw, 640px\"\n\t\t\t\t\t\t\t\t\t\t\t\tloading=\"lazy\"\n\t\t\t\t\t\tdecoding=\"async\"\n\t\t\t\t\t>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__story-content-overlay\">\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__title\">\n\t\t\t\t\tAfinal, quanto o Futebol Solid\u00e1rio arrecadou?\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"story-content-overlay__author\">\n\t\t\t\t\tPor Carolina Jacob\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"web-stories-list__archive-link\">\n\t\t\t<a href=\"https:\/\/www.acordocerto.com.br\/blog\/web-stories\/\">\n\t\t\t\tVisualizando todos Stories\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\n\n<p> <\/p>\n\n\n\n<p><strong>FAQ: Perguntas frequentes<\/strong>&nbsp;<\/p>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1662063393045\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><strong>Como saber se estou inscrito no cadastro \u00fanico?<\/strong>\u00a0<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Para ser se o seu cadastro foi feito com sucesso no Cad\u00danico, basta fazer uma consulta no site ou aplicativo oficiais Meu Cad\u00danico. \u00c9 poss\u00edvel tamb\u00e9m conferir o cadastro fazendo uma liga\u00e7\u00e3o gratuita para o n\u00famero 0800 707 2003 (essa liga\u00e7\u00e3o deve ser feita de segunda a sexta das 7 \u00e0s 19h, e aos s\u00e1bados, domingos e feriados das 10h \u00e0s 16h).<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1662063400981\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><strong>O que \u00e9 NIS no CAD\u00danico?<\/strong>\u00a0<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>o NIS \u00e9 o N\u00famero de Identifica\u00e7\u00e3o Social que indica o n\u00famero de inscri\u00e7\u00e3o no Cadastro \u00danico (Cad\u00danico). \u00c9 poss\u00edvel consultar o NIS no <a href=\"https:\/\/apps.apple.com\/br\/app\/cadastro-%C3%BAnico\/id1605659516\" target=\"_blank\" rel=\"noreferrer noopener\">aplicativo Meu Cad\u00danico.<\/a> \u00a0<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1662063402264\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><strong>Posso atualizar o Cad\u00fanico pela internet?<\/strong>\u00a0<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Sim, atrav\u00e9s do aplicativo Meu Cad\u00danico (que pode ser baixado nos celulares Android ou IOS) ou ent\u00e3o pelo site oficial do Cadastro \u00danico.\u00a0<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p><strong>Leia tamb\u00e9m:<\/strong><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list wp-block-latest-posts\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.acordocerto.com.br\/blog\/consultar-cpf-de-outra-pessoa\/\">Consultar CPF de outra pessoa: veja 7 limites legais para n\u00e3o expor dados<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.acordocerto.com.br\/blog\/calculadora-de-hora-trabalhada\/\">Calculadora de Hora Trabalhada: Quanto Vale Cada Minuto do Seu Tempo?<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.acordocerto.com.br\/blog\/ipva-atrasado\/\">IPVA atrasado 2026: veja como regularizar e proteger seu ve\u00edculo de juros, d\u00edvida ativa e apreens\u00e3o<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.acordocerto.com.br\/blog\/divida-pode-bloquear-ou-penhorar-salario\/\">D\u00edvida pode bloquear ou penhorar sal\u00e1rio? Entenda o que a lei permite<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.acordocerto.com.br\/blog\/cnh-pai-d-egua-para\/\">CNH Pai D\u2019\u00e9gua 2026: como funciona e quem pode se inscrever na CNH Social do Par\u00e1<\/a><\/li>\n<\/ul>\n\n\n<p> &nbsp;<\/p>\n\n\n\n<p><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 Cadastro \u00danico (Cad\u00danico)? Entenda como funciona e veja como cadastrar toda a sua fam\u00edlia de forma gratuita para receber aux\u00edlios sociais do Governo. <\/p>\n","protected":false},"author":10,"featured_media":4702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[33],"tags":[627],"class_list":["post-4698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direitos-e-beneficios","tag-auxilio-do-governo"],"acf":[],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":12,"sum_votes":51},"_links":{"self":[{"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/posts\/4698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4698"}],"version-history":[{"count":23,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/posts\/4698\/revisions"}],"predecessor-version":[{"id":16124,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/posts\/4698\/revisions\/16124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/media\/4702"}],"wp:attachment":[{"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.acordocerto.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}